{"id":55,"date":"2019-01-10T15:35:12","date_gmt":"2019-01-10T15:35:12","guid":{"rendered":"http:\/\/sisa.archaeological.science\/index.php\/newsletter\/"},"modified":"2019-01-10T15:35:12","modified_gmt":"2019-01-10T15:35:12","slug":"newsletter","status":"publish","type":"page","link":"http:\/\/sisa.archaeological.science\/index.php\/newsletter\/","title":{"rendered":"Newsletter"},"content":{"rendered":"<div class=\"tnp tnp-subscription \">\n<form method=\"post\" action=\"http:\/\/sisa.archaeological.science\/wp-admin\/admin-ajax.php?action=tnp&amp;na=s\">\n<input type=\"hidden\" name=\"nlang\" value=\"\">\n<div class=\"tnp-field tnp-field-firstname\"><label for=\"tnp-1\">First name or full name<\/label>\n<input class=\"tnp-name\" type=\"text\" name=\"nn\" id=\"tnp-1\" value=\"\" placeholder=\"\"><\/div>\n<div class=\"tnp-field tnp-field-email\"><label for=\"tnp-2\">Email<\/label>\n<input class=\"tnp-email\" type=\"email\" name=\"ne\" id=\"tnp-2\" value=\"\" placeholder=\"\" required><\/div>\n<div class=\"tnp-field tnp-privacy-field\"><label><input type=\"checkbox\" name=\"ny\" required class=\"tnp-privacy\"> By continuing, you accept the privacy policy<\/label><\/div><div class=\"tnp-field tnp-field-button\" style=\"text-align: left\"><input class=\"tnp-submit\" type=\"submit\" value=\"Subscribe\" style=\"\">\n<\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/pages\/55"}],"collection":[{"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":0,"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/pages\/55\/revisions"}],"wp:attachment":[{"href":"http:\/\/sisa.archaeological.science\/index.php\/wp-json\/wp\/v2\/media?parent=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}